{"id":883,"date":"2021-02-19T12:35:52","date_gmt":"2021-02-19T11:35:52","guid":{"rendered":"https:\/\/www.vorderachsen.at\/?post_type=product&#038;p=883"},"modified":"2021-10-20T14:24:29","modified_gmt":"2021-10-20T12:24:29","slug":"gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx","status":"publish","type":"product","link":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/","title":{"rendered":"Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX"},"content":{"rendered":"<p>Gleitlagerbuchse f\u00fcr die Bolzen mit d=40mm<\/p>\n<p>40 x 44 x 30<\/p>\n<p>Passend bei allen 3 Bolzen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gleitlagerbuchse f\u00fcr die Bolzen mit d=40mm 40 x 44 x 30 Passend bei allen 3 Bolzen<\/p>\n","protected":false},"featured_media":884,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[50],"product_tag":[],"class_list":{"0":"post-883","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-lager","7":"product_cat_axis-carraro-2025","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX - D&amp;F Vorderachsen Ehrengruber<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX - D&amp;F Vorderachsen Ehrengruber\" \/>\n<meta property=\"og:description\" content=\"Gleitlagerbuchse f\u00fcr die Bolzen mit d=40mm 40 x 44 x 30 Passend bei allen 3 Bolzen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;F Vorderachsen Ehrengruber\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-20T12:24:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vorderachsen.at\/wp-content\/uploads\/2021\/02\/DSC09032-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/\",\"url\":\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/\",\"name\":\"Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX - D&amp;F Vorderachsen Ehrengruber\",\"isPartOf\":{\"@id\":\"https:\/\/www.vorderachsen.at\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vorderachsen.at\/wp-content\/uploads\/2021\/02\/DSC09032-scaled.jpg\",\"datePublished\":\"2021-02-19T11:35:52+00:00\",\"dateModified\":\"2021-10-20T12:24:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#primaryimage\",\"url\":\"https:\/\/www.vorderachsen.at\/wp-content\/uploads\/2021\/02\/DSC09032-scaled.jpg\",\"contentUrl\":\"https:\/\/www.vorderachsen.at\/wp-content\/uploads\/2021\/02\/DSC09032-scaled.jpg\",\"width\":2560,\"height\":1714,\"caption\":\"SONY DSC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.vorderachsen.at\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online Shop\",\"item\":\"https:\/\/www.vorderachsen.at\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vorderachsen.at\/de\/#website\",\"url\":\"https:\/\/www.vorderachsen.at\/de\/\",\"name\":\"D&amp;F Vorderachsen Ehrengruber\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vorderachsen.at\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX - D&amp;F Vorderachsen Ehrengruber","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/","og_locale":"de_DE","og_type":"article","og_title":"Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX - D&amp;F Vorderachsen Ehrengruber","og_description":"Gleitlagerbuchse f\u00fcr die Bolzen mit d=40mm 40 x 44 x 30 Passend bei allen 3 Bolzen","og_url":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/","og_site_name":"D&amp;F Vorderachsen Ehrengruber","article_modified_time":"2021-10-20T12:24:29+00:00","og_image":[{"width":2560,"height":1714,"url":"https:\/\/www.vorderachsen.at\/wp-content\/uploads\/2021\/02\/DSC09032-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/","url":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/","name":"Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX - D&amp;F Vorderachsen Ehrengruber","isPartOf":{"@id":"https:\/\/www.vorderachsen.at\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#primaryimage"},"image":{"@id":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vorderachsen.at\/wp-content\/uploads\/2021\/02\/DSC09032-scaled.jpg","datePublished":"2021-02-19T11:35:52+00:00","dateModified":"2021-10-20T12:24:29+00:00","breadcrumb":{"@id":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#primaryimage","url":"https:\/\/www.vorderachsen.at\/wp-content\/uploads\/2021\/02\/DSC09032-scaled.jpg","contentUrl":"https:\/\/www.vorderachsen.at\/wp-content\/uploads\/2021\/02\/DSC09032-scaled.jpg","width":2560,"height":1714,"caption":"SONY DSC"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vorderachsen.at\/de\/produkt\/gleitlagerbuchse-gleitbuchse-carraro-2025-340453a1-cvt-cvx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.vorderachsen.at\/de\/"},{"@type":"ListItem","position":2,"name":"Online Shop","item":"https:\/\/www.vorderachsen.at\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Gleitlagerbuchse Bundbuchse klein Gleitbuchse Carraro 2025 340453A1 CVT CVX"}]},{"@type":"WebSite","@id":"https:\/\/www.vorderachsen.at\/de\/#website","url":"https:\/\/www.vorderachsen.at\/de\/","name":"D&amp;F Vorderachsen Ehrengruber","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vorderachsen.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.vorderachsen.at\/de\/wp-json\/wp\/v2\/product\/883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vorderachsen.at\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vorderachsen.at\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vorderachsen.at\/de\/wp-json\/wp\/v2\/media\/884"}],"wp:attachment":[{"href":"https:\/\/www.vorderachsen.at\/de\/wp-json\/wp\/v2\/media?parent=883"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vorderachsen.at\/de\/wp-json\/wp\/v2\/product_brand?post=883"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vorderachsen.at\/de\/wp-json\/wp\/v2\/product_cat?post=883"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vorderachsen.at\/de\/wp-json\/wp\/v2\/product_tag?post=883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}